{"id":17674,"date":"2022-03-19T15:34:34","date_gmt":"2022-03-19T15:03:47","guid":{"rendered":"https:\/\/apimat.ch\/?post_type=product&#038;p=17674"},"modified":"2024-10-23T10:10:57","modified_gmt":"2024-10-23T08:10:57","slug":"beutelheber-fuer-die-platzierung-der-futterteig","status":"publish","type":"product","link":"https:\/\/apimat.ch\/de\/produit\/beutelheber-fuer-die-platzierung-der-futterteig\/","title":{"rendered":"Hebesack, um das Futterteig aufzulegen und es den Bienen leicht zug\u00e4nglich zu machen"},"content":{"rendered":"<p>Hebesack, um das Futterteig aufzulegen und es den Bienen leicht zug\u00e4nglich zu machen<\/p>\n<p class=\"p1\"><b>DIE PREISE SIND JE NACH MENGE DEGRESSIV.<\/b><\/p>\n<p class=\"p1\"><b>F\u00fcr weitere Informationen kontaktieren Sie mich bitte.<\/b><\/p>\n<p class=\"p2\"><span class=\"s1\"><a href=\"mailto:info@apimat.ch\"><b>info@apimat.ch<\/b><\/a><\/span><\/p>\n<p class=\"p1\"><b>Telefon: 076 213 80 33<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hebesack, um das Futterteig aufzulegen und es den Bienen leicht zug\u00e4nglich zu machen DIE PREISE SIND JE NACH MENGE DEGRESSIV. F\u00fcr weitere Informationen kontaktieren Sie mich bitte. info@apimat.ch Telefon: 076 213 80 33<\/p>\n","protected":false},"featured_media":17679,"template":"","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false},"product_cat":[94],"product_tag":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/apimat.ch\/de\/wp-json\/wp\/v2\/product\/17674"}],"collection":[{"href":"https:\/\/apimat.ch\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/apimat.ch\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/apimat.ch\/de\/wp-json\/wp\/v2\/media\/17679"}],"wp:attachment":[{"href":"https:\/\/apimat.ch\/de\/wp-json\/wp\/v2\/media?parent=17674"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/apimat.ch\/de\/wp-json\/wp\/v2\/product_cat?post=17674"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/apimat.ch\/de\/wp-json\/wp\/v2\/product_tag?post=17674"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}